{"id":230240,"date":"2025-07-15T18:28:21","date_gmt":"2025-07-15T18:28:21","guid":{"rendered":"http:\/\/teammototec.com\/test\/producto\/valvula-de-admision-psychic-acero-xu-09521i\/"},"modified":"2025-07-15T18:28:55","modified_gmt":"2025-07-15T18:28:55","slug":"valvula-de-admision-psychic-acero-xu-09521i","status":"publish","type":"product","link":"https:\/\/teammototec.com\/test\/producto\/valvula-de-admision-psychic-acero-xu-09521i\/","title":{"rendered":"V\u00c1LVULA DE ADMISI\u00d3N PSYCHIC ACERO XU-09521i"},"content":{"rendered":"<p>V\u00e1lvulas de repuesto OEM &#8211; est\u00e1n fabricadas seg\u00fan las especificaciones OEM con acero SUH3HT para una mayor resistencia a la corrosi\u00f3n y a la oxidaci\u00f3n.<br \/>\nV\u00e1lvulas de rendimiento &#8211; cuentan con una construcci\u00f3n forjada de una sola pieza, recubrimiento de nitruro, radio modificado, pulido de remolino, v\u00e1stagos cromados y puntas de estelita. Esto proporciona una fricci\u00f3n reducida para revoluciones m\u00e1s r\u00e1pidas\/altas y una vida m\u00e1s larga de la v\u00e1lvula.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>V\u00e1lvulas de repuesto OEM &#8211; est\u00e1n fabricadas seg\u00fan las especificaciones OEM con acero SUH3HT para una mayor resistencia a la corrosi\u00f3n y a la oxidaci\u00f3n. V\u00e1lvulas de rendimiento &#8211; cuentan con una construcci\u00f3n forjada de una sola pieza, recubrimiento de nitruro, radio modificado, pulido de remolino, v\u00e1stagos cromados y puntas de estelita. Esto proporciona una [&hellip;]<\/p>\n","protected":false},"featured_media":229915,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_cat":[877],"product_tag":[1576],"class_list":["post-230240","product","type-product","status-publish","has-post-thumbnail","product_cat-valvulas-de-motor","product_tag-psychic","pa_ano-923","pa_ano-924","pa_ano-925","pa_ano-926","pa_ano-927","pa_ano-928","pa_ano-929","pa_ano-930","pa_ano-931","pa_ano-895","pa_ano-896","pa_ano-932","pa_ano-933","pa_marca-gas-gas","pa_marca-yamaha","pa_modelo-ec-450-f","pa_modelo-wr-450-f","pa_modelo-yz-450-f","pa_tipo-de-vehiculo-dirt-bike","first","instock","shipping-taxable","purchasable","product-type-variable"],"_links":{"self":[{"href":"https:\/\/teammototec.com\/test\/wp-json\/wp\/v2\/product\/230240","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teammototec.com\/test\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/teammototec.com\/test\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/teammototec.com\/test\/wp-json\/wp\/v2\/comments?post=230240"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teammototec.com\/test\/wp-json\/wp\/v2\/media\/229915"}],"wp:attachment":[{"href":"https:\/\/teammototec.com\/test\/wp-json\/wp\/v2\/media?parent=230240"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/teammototec.com\/test\/wp-json\/wp\/v2\/product_cat?post=230240"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/teammototec.com\/test\/wp-json\/wp\/v2\/product_tag?post=230240"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}